{"id":425,"date":"2007-02-04T00:01:44","date_gmt":"2007-02-03T23:01:44","guid":{"rendered":"http:\/\/www.maurograziani.org\/wordpress\/?p=425"},"modified":"2025-08-22T18:14:35","modified_gmt":"2025-08-22T16:14:35","slug":"piano-phase","status":"publish","type":"post","link":"https:\/\/maurograziani.org\/wordpress\/archives\/425","title":{"rendered":"Piano phase"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Io non sono un fan della musica minimale, per\u00f2 questo Piano phase di Steve Reich del 1967 \u00e8 importante e coinvolgente. Si tratta del primo brano totalmente strumentale in cui Reich utilizza la tecnica del phasing, fino ad allora usata solo in elettronica.<br \/>\nIl phasing pu\u00f2 essere descritto semplicemente come il suonare due frasi identiche con una leggera differenza metronomica (l&#8217;una appena pi\u00f9 veloce dell&#8217;altra). Di conseguenza le due frasi dapprima suonano all&#8217;unisono. Poi, quando la differenza \u00e8 ancora molto piccola, si ha una strana percezione, come se le note si allungassero o avessero un riverbero. In seguito la differenza diventa chiaramente percepibile: la melodia si sdoppia anche come numero di note (2 note nel tempo di una). Infine la melodia ritorna in fase, ma mentre un pianista suona la prima nota, l&#8217;altro suona la seconda: abbiamo cos\u00ec dei bicordi al posto dell&#8217;unisono iniziale.<br \/>\nIn questo brano il processo continua attraverso vari stadi di fase e controfase, fino a quando i due pianisti sono sfasati al punto in cui la prima nota dell&#8217;uno si sovrappone all&#8217;ultima dell&#8217;altro. Cos\u00ec una frasetta di 12 note genera un brano di circa 20 minuti.<br \/>\nFino ad oggi, il brano era per due pianoforti e due pianisti in primo luogo perch\u00e9 le note sono le stesse e in secondo luogo perch\u00e9, pur essendo la frase molto facile, sembrava impossibile che una persona sola potesse suonarla a due velocit\u00e0 di poco diverse. Invece in questa esecuzione dell&#8217;ottobre 2006, il russo Peter Aidu fa tutto da solo, creando i due flussi sonori con le due mani su due pianoforti (e candidandosi per il premio schizo &#8211; scherzi a parte, quello che fa \u00e8 neurologicamte pazzesco, anche perch\u00e9, mentre i due pianisti usano entrambi la destra, lui non pu\u00f2).<br \/>\nMore in <a href=\"http:\/\/www.archive.org\/details\/top.09\">this Internet Archive page<\/a>.<\/p>\n<p>Steve Reich &#8211; <a href=\"http:\/\/ia601309.us.archive.org\/18\/items\/top.09\/top.09_Steve_Reich_Piano_Phase_performed_by_Peter_Aidu.mp3\" target=\"_blank\" rel=\"noopener\">Piano phase<\/a> (1967) &#8211; Peter Aidu, 2 pianos<br \/>\n<a href=\"https:\/\/archive.org\/details\/top.09\" target=\"_blank\" rel=\"noopener\">Download<\/a> mp3.<\/p>\n<div class=\"related-posts\">\n<div id=\"related-posts-MRP_all\" class=\"related-posts-type\">\n<h3>RELATED:<\/h3>\n<ul>\n<li><a href=\"https:\/\/maurograziani.org\/wordpress\/archives\/3466\">Music for 18 musicians<\/a><\/li>\n<\/ul><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Io non sono un fan della musica minimale, per\u00f2 questo Piano phase di Steve Reich del 1967 \u00e8 importante e coinvolgente. Si tratta del primo brano totalmente strumentale in cui Reich utilizza la tecnica del phasing, fino ad allora usata &hellip; <a href=\"https:\/\/maurograziani.org\/wordpress\/archives\/425\">Continua a leggere<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[210],"tags":[654,644],"class_list":["post-425","post","type-post","status-publish","format-standard","hentry","category-strumentale-mus","tag-minimal","tag-reich"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/posts\/425"}],"collection":[{"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/comments?post=425"}],"version-history":[{"count":3,"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/posts\/425\/revisions"}],"predecessor-version":[{"id":18597,"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/posts\/425\/revisions\/18597"}],"wp:attachment":[{"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/media?parent=425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/categories?post=425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurograziani.org\/wordpress\/wp-json\/wp\/v2\/tags?post=425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}